{"id":139076,"date":"2025-10-22T15:32:31","date_gmt":"2025-10-22T15:32:31","guid":{"rendered":"https:\/\/gloopbaby.com\/?post_type=product&#038;p=139076"},"modified":"2026-04-13T14:45:23","modified_gmt":"2026-04-13T14:45:23","slug":"gigoteuse-dete-sleepy-6-24-mois-copia","status":"publish","type":"product","link":"https:\/\/gloopbaby.com\/fr\/produit\/collections-fr\/little-garden-fr\/gigoteuse-dete-sleepy-6-24-mois-copia\/","title":{"rendered":"Gigoteuse d&rsquo;\u00e9t\u00e9 Little Garden 6-24 mois"},"content":{"rendered":"<pre id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" tabindex=\"-1\" role=\"text\" data-placeholder=\"Tradu\u00e7\u00e3o\" data-ved=\"2ahUKEwjNvKywgeuTAxXKU6QEHbuYEh4Q3ewLegQIDBAV\" aria-label=\"Texto traduzido: La gigoteuse d'\u00e9t\u00e9 gloop! offre \u00e0 votre b\u00e9b\u00e9 un sommeil s\u00fbr et confortable d\u00e8s ses premiers jours. Id\u00e9ale pour les berceaux et les lits \u00e0 barreaux, elle convient aux b\u00e9b\u00e9s de 6 \u00e0 24 mois. L\u00e9g\u00e8re, respirante et dot\u00e9e d'un indice TOG de 0,5, elle garde votre b\u00e9b\u00e9 bien au chaud sans le faire transpirer.\r\n\r\nConfectionn\u00e9e en coton 100 % biologique certifi\u00e9, sa mati\u00e8re est ultra-douce et respecte la peau sensible des nouveau-n\u00e9s. Sa fermeture sur le devant facilite l'habillage et le d\u00e9shabillage, ce qui la rend parfaite pour une utilisation dans un berceau, un lit \u00e0 barreaux ou un lit d'enfant de 6 \u00e0 24 mois.\r\n\r\nFabriqu\u00e9e avec soin au Portugal, cette gigoteuse l\u00e9g\u00e8re est un indispensable de la trousse de naissance pour l'\u00e9t\u00e9.\r\n\r\nDimensions : 95 x 45 cm\r\nIndice de chaleur (TOG) : 0,5 - id\u00e9al pour les nuits chaudes\r\n\r\nCaract\u00e9ristiques principales :\r\n\r\nId\u00e9al pour les b\u00e9b\u00e9s de 6 \u00e0 24 mois\r\n\r\nExt\u00e9rieur en coton biologique certifi\u00e9\r\n\r\nInt\u00e9rieur doux et confortable en polyester\r\n\r\nFermeture \u00e9clair pratique pour habiller et d\u00e9shabiller facilement\r\n\r\nFabriqu\u00e9 au Portugal\r\n\r\nOffrez \u00e0 votre b\u00e9b\u00e9 des nuits paisibles et confortables cet \u00e9t\u00e9.\"><span class=\"Y2IQFc\" lang=\"fr\">La gigoteuse d'\u00e9t\u00e9 gloop! offre \u00e0 votre b\u00e9b\u00e9 un sommeil s\u00fbr et confortable d\u00e8s ses premiers jours. Id\u00e9ale pour les berceaux et les lits \u00e0 barreaux, elle convient aux b\u00e9b\u00e9s de 6 \u00e0 24 mois. L\u00e9g\u00e8re, respirante et dot\u00e9e d'un indice TOG de 0.5, elle garde votre b\u00e9b\u00e9 bien au chaud sans le faire transpirer.\r\n\r\nConfectionn\u00e9e en coton 100% biologique certifi\u00e9, sa mati\u00e8re est ultra-douce et respecte la peau sensible des nouveau-n\u00e9s. Sa fermeture sur le devant facilite l'habillage et le d\u00e9shabillage, ce qui la rend parfaite pour une utilisation dans un berceau, un lit \u00e0 barreaux ou un lit d'enfant de 6 \u00e0 24 mois.\r\n\r\nFabriqu\u00e9e avec soin au Portugal, cette gigoteuse l\u00e9g\u00e8re est un indispensable de la trousse de naissance pour l'\u00e9t\u00e9.\r\n\r\nDimensions : 95x45cm\r\nIndice de chaleur (TOG) : 0.5 - id\u00e9al pour les nuits chaudes\r\n\r\n<strong>Caract\u00e9ristiques principales:<\/strong>\r\n\r\nId\u00e9al pour les b\u00e9b\u00e9s de 6 \u00e0 24 mois\r\n\r\nExt\u00e9rieur en coton biologique certifi\u00e9\r\n\r\nFermeture \u00e9clair pratique pour habiller et d\u00e9shabiller facilement\r\n\r\nFabriqu\u00e9 au Portugal\r\n\r\nOffrez \u00e0 votre b\u00e9b\u00e9 des nuits paisibles et confortables cet \u00e9t\u00e9.<\/span><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>La gigoteuse d&rsquo;\u00e9t\u00e9 gloop! offre \u00e0 votre b\u00e9b\u00e9 un sommeil s\u00fbr et confortable d\u00e8s ses premiers jours. Id\u00e9ale pour les berceaux et les lits \u00e0 barreaux, elle convient aux b\u00e9b\u00e9s de 6 \u00e0 24 mois. L\u00e9g\u00e8re, respirante et dot\u00e9e d&rsquo;un indice TOG de 0.5, elle garde votre b\u00e9b\u00e9 bien au chaud sans le faire transpirer. [&hellip;]<\/p>\n","protected":false},"featured_media":141232,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1582,1479,1481,1480,1478,1942],"product_tag":[],"class_list":["post-139076","product","type-product","status-publish","has-post-thumbnail","product_cat-collections-fr","product_cat-gigoteuse-fr","product_cat-gigoteuse-6-24m","product_cat-gigoteuse-dete-fr","product_cat-home-and-sleep-fr","product_cat-little-garden-fr","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gigoteuse d&#039;\u00e9t\u00e9 Little Garden 6-24 mois - Gloop Baby<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gloopbaby.com\/fr\/produit\/collections-fr\/little-garden-fr\/gigoteuse-dete-sleepy-6-24-mois-copia\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gigoteuse d&#039;\u00e9t\u00e9 Little Garden 6-24 mois - Gloop Baby\" \/>\n<meta property=\"og:description\" content=\"La gigoteuse d&#039;\u00e9t\u00e9 gloop! offre \u00e0 votre b\u00e9b\u00e9 un sommeil s\u00fbr et confortable d\u00e8s ses premiers jours. Id\u00e9ale pour les berceaux et les lits \u00e0 barreaux, elle convient aux b\u00e9b\u00e9s de 6 \u00e0 24 mois. L\u00e9g\u00e8re, respirante et dot\u00e9e d&#039;un indice TOG de 0.5, elle garde votre b\u00e9b\u00e9 bien au chaud sans le faire transpirer. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gloopbaby.com\/fr\/produit\/collections-fr\/little-garden-fr\/gigoteuse-dete-sleepy-6-24-mois-copia\/\" \/>\n<meta property=\"og:site_name\" content=\"Gloop Baby\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-13T14:45:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gloopbaby.com\/wp-content\/uploads\/2025\/10\/saco-dormir-verao-little-garden.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gloopbaby.com\\\/fr\\\/produit\\\/collections-fr\\\/little-garden-fr\\\/gigoteuse-dete-sleepy-6-24-mois-copia\\\/\",\"url\":\"https:\\\/\\\/gloopbaby.com\\\/fr\\\/produit\\\/collections-fr\\\/little-garden-fr\\\/gigoteuse-dete-sleepy-6-24-mois-copia\\\/\",\"name\":\"Gigoteuse d'\u00e9t\u00e9 Little Garden 6-24 mois - Gloop Baby\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gloopbaby.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gloopbaby.com\\\/fr\\\/produit\\\/collections-fr\\\/little-garden-fr\\\/gigoteuse-dete-sleepy-6-24-mois-copia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gloopbaby.com\\\/fr\\\/produit\\\/collections-fr\\\/little-garden-fr\\\/gigoteuse-dete-sleepy-6-24-mois-copia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gloopbaby.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/saco-dormir-verao-little-garden.jpg\",\"datePublished\":\"2025-10-22T15:32:31+00:00\",\"dateModified\":\"2026-04-13T14:45:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gloopbaby.com\\\/fr\\\/produit\\\/collections-fr\\\/little-garden-fr\\\/gigoteuse-dete-sleepy-6-24-mois-copia\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gloopbaby.com\\\/fr\\\/produit\\\/collections-fr\\\/little-garden-fr\\\/gigoteuse-dete-sleepy-6-24-mois-copia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/gloopbaby.com\\\/fr\\\/produit\\\/collections-fr\\\/little-garden-fr\\\/gigoteuse-dete-sleepy-6-24-mois-copia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gloopbaby.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/saco-dormir-verao-little-garden.jpg\",\"contentUrl\":\"https:\\\/\\\/gloopbaby.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/saco-dormir-verao-little-garden.jpg\",\"width\":600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gloopbaby.com\\\/fr\\\/produit\\\/collections-fr\\\/little-garden-fr\\\/gigoteuse-dete-sleepy-6-24-mois-copia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/gloopbaby.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/gloopbaby.com\\\/loja\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gigoteuse d&#8217;\u00e9t\u00e9 Little Garden 6-24 mois\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gloopbaby.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/gloopbaby.com\\\/fr\\\/\",\"name\":\"Gloop Baby\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/gloopbaby.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gloopbaby.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gloopbaby.com\\\/fr\\\/#organization\",\"name\":\"Gloop Baby\",\"url\":\"https:\\\/\\\/gloopbaby.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/gloopbaby.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gloopbaby.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/gloop-logo.svg\",\"contentUrl\":\"https:\\\/\\\/gloopbaby.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/gloop-logo.svg\",\"width\":100,\"height\":100,\"caption\":\"Gloop Baby\"},\"image\":{\"@id\":\"https:\\\/\\\/gloopbaby.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gigoteuse d'\u00e9t\u00e9 Little Garden 6-24 mois - Gloop Baby","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gloopbaby.com\/fr\/produit\/collections-fr\/little-garden-fr\/gigoteuse-dete-sleepy-6-24-mois-copia\/","og_locale":"fr_FR","og_type":"article","og_title":"Gigoteuse d'\u00e9t\u00e9 Little Garden 6-24 mois - Gloop Baby","og_description":"La gigoteuse d'\u00e9t\u00e9 gloop! offre \u00e0 votre b\u00e9b\u00e9 un sommeil s\u00fbr et confortable d\u00e8s ses premiers jours. Id\u00e9ale pour les berceaux et les lits \u00e0 barreaux, elle convient aux b\u00e9b\u00e9s de 6 \u00e0 24 mois. L\u00e9g\u00e8re, respirante et dot\u00e9e d'un indice TOG de 0.5, elle garde votre b\u00e9b\u00e9 bien au chaud sans le faire transpirer. [&hellip;]","og_url":"https:\/\/gloopbaby.com\/fr\/produit\/collections-fr\/little-garden-fr\/gigoteuse-dete-sleepy-6-24-mois-copia\/","og_site_name":"Gloop Baby","article_modified_time":"2026-04-13T14:45:23+00:00","og_image":[{"width":600,"height":900,"url":"https:\/\/gloopbaby.com\/wp-content\/uploads\/2025\/10\/saco-dormir-verao-little-garden.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gloopbaby.com\/fr\/produit\/collections-fr\/little-garden-fr\/gigoteuse-dete-sleepy-6-24-mois-copia\/","url":"https:\/\/gloopbaby.com\/fr\/produit\/collections-fr\/little-garden-fr\/gigoteuse-dete-sleepy-6-24-mois-copia\/","name":"Gigoteuse d'\u00e9t\u00e9 Little Garden 6-24 mois - Gloop Baby","isPartOf":{"@id":"https:\/\/gloopbaby.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gloopbaby.com\/fr\/produit\/collections-fr\/little-garden-fr\/gigoteuse-dete-sleepy-6-24-mois-copia\/#primaryimage"},"image":{"@id":"https:\/\/gloopbaby.com\/fr\/produit\/collections-fr\/little-garden-fr\/gigoteuse-dete-sleepy-6-24-mois-copia\/#primaryimage"},"thumbnailUrl":"https:\/\/gloopbaby.com\/wp-content\/uploads\/2025\/10\/saco-dormir-verao-little-garden.jpg","datePublished":"2025-10-22T15:32:31+00:00","dateModified":"2026-04-13T14:45:23+00:00","breadcrumb":{"@id":"https:\/\/gloopbaby.com\/fr\/produit\/collections-fr\/little-garden-fr\/gigoteuse-dete-sleepy-6-24-mois-copia\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gloopbaby.com\/fr\/produit\/collections-fr\/little-garden-fr\/gigoteuse-dete-sleepy-6-24-mois-copia\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/gloopbaby.com\/fr\/produit\/collections-fr\/little-garden-fr\/gigoteuse-dete-sleepy-6-24-mois-copia\/#primaryimage","url":"https:\/\/gloopbaby.com\/wp-content\/uploads\/2025\/10\/saco-dormir-verao-little-garden.jpg","contentUrl":"https:\/\/gloopbaby.com\/wp-content\/uploads\/2025\/10\/saco-dormir-verao-little-garden.jpg","width":600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/gloopbaby.com\/fr\/produit\/collections-fr\/little-garden-fr\/gigoteuse-dete-sleepy-6-24-mois-copia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/gloopbaby.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/gloopbaby.com\/loja\/"},{"@type":"ListItem","position":3,"name":"Gigoteuse d&#8217;\u00e9t\u00e9 Little Garden 6-24 mois"}]},{"@type":"WebSite","@id":"https:\/\/gloopbaby.com\/fr\/#website","url":"https:\/\/gloopbaby.com\/fr\/","name":"Gloop Baby","description":"","publisher":{"@id":"https:\/\/gloopbaby.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gloopbaby.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/gloopbaby.com\/fr\/#organization","name":"Gloop Baby","url":"https:\/\/gloopbaby.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/gloopbaby.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/gloopbaby.com\/wp-content\/uploads\/2023\/06\/gloop-logo.svg","contentUrl":"https:\/\/gloopbaby.com\/wp-content\/uploads\/2023\/06\/gloop-logo.svg","width":100,"height":100,"caption":"Gloop Baby"},"image":{"@id":"https:\/\/gloopbaby.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/gloopbaby.com\/fr\/wp-json\/wp\/v2\/product\/139076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gloopbaby.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gloopbaby.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gloopbaby.com\/fr\/wp-json\/wp\/v2\/comments?post=139076"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gloopbaby.com\/fr\/wp-json\/wp\/v2\/media\/141232"}],"wp:attachment":[{"href":"https:\/\/gloopbaby.com\/fr\/wp-json\/wp\/v2\/media?parent=139076"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gloopbaby.com\/fr\/wp-json\/wp\/v2\/product_brand?post=139076"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gloopbaby.com\/fr\/wp-json\/wp\/v2\/product_cat?post=139076"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gloopbaby.com\/fr\/wp-json\/wp\/v2\/product_tag?post=139076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}